{"id":10,"date":"2023-05-17T06:19:24","date_gmt":"2023-05-17T06:19:24","guid":{"rendered":"https:\/\/www.americanwebbuilders.com\/blog\/?page_id=10"},"modified":"2026-08-03T16:16:51","modified_gmt":"2026-08-03T16:16:51","slug":"home","status":"publish","type":"page","link":"https:\/\/www.americanwebbuilders.com\/blog\/","title":{"rendered":"home"},"content":{"rendered":"[vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; id=&#8221;nec-sec&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;]<style type=\"text\/css\">#nectar-slider-instance-1, #nectar-slider-instance-1 .swiper-container { min-height: 250px; } <\/style><div  data-transition=\"slide\" data-overall_style=\"classic\" data-flexible-height=\"true\" data-animate-in-effect=\"none\" data-fullscreen=\"false\" data-button-sizing=\"regular\" data-button-styling=\"btn_with_count\" data-autorotate=\"\" data-parallax=\"false\" data-parallax-disable-mobile=\"\" data-caption-trans=\"fade_in_from_bottom\" data-parallax-style=\"bg_only\" data-bg-animation=\"none\" data-full-width=\"false\" class=\"nectar-slider-wrap \" id=\"nectar-slider-instance-1\"><div class=\"swiper-container\"  data-tho=\"auto\" data-tco=\"auto\" data-pho=\"auto\" data-pco=\"auto\" data-loop=\"false\" data-height=\"500\" data-min-height=\"250\" data-arrows=\"false\" data-bullets=\"false\" data-bullet_style=\"see_through\" data-bullet_position=\"bottom\" data-desktop-swipe=\"false\" data-settings=\"\"> <div class=\"swiper-wrapper\"><div class=\"swiper-slide\" data-desktop-content-width=\"auto\" data-tablet-content-width=\"auto\" data-bg-alignment=\"top\" data-color-scheme=\"light\" data-x-pos=\"centered\" data-y-pos=\"middle\" ><div class=\"slide-bg-wrap\"><div class=\"image-bg\" style=\"background-image: url(https:\/\/www.americanwebbuilders.com\/blog\/wp-content\/uploads\/2023\/06\/banner-bg1.webp);\"> &nbsp; <\/div><\/div><div class=\"container\">\n\t\t\t\t\t\t<div class=\"content\"><h2 class=\"ns-heading-el\">The American Web Builders Blog<\/h2><p  ><span>Every week, we post the latest news, updates, and insights on projects, people, and places that move us.<\/span><\/p><\/div>\n\t\t\t\t\t\t\t\t<\/div><!--\/container--><div class=\"video-texture \"> <span class=\"ie-fix\"><\/span> <\/div><\/div> <!--\/swiper-slide--><\/div><div class=\"nectar-slider-loading \"> <span class=\"loading-icon none\">   <\/span> <\/div> <\/div> \n\t\t\t\t\t\n\t\t\t\t\t<\/div>[\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;60&#8243; top_padding_tablet=&#8221;30&#8243; bottom_padding_tablet=&#8221;30&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; id=&#8221;k-sec&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_widget_sidebar sidebar_id=&#8221;nectar-extra-sidebar&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_raw_html el_class=&#8221;ra&#8221;]JTNDZGl2JTIwY2xhc3MlM0QlMjJpY24lMjIlM0UlMEElM0NoNCUzRUZvbGxvdyUyMFVzJTIwT24lM0MlMkZoNCUzRSUwQSUzQ3VsJTNFJTBBJTIwJTNDbGklM0UlMEElMjAlMjAlMjAlM0NhJTIwaHJlZiUzRCUyMmh0dHBzJTNBJTJGJTJGd3d3LmZhY2Vib29rLmNvbSUyRmFtZXJpY2Fud2ViYnVpbGRlcnMlM0ZtaWJleHRpZCUzRExRUUo0ZCUyMiUzRSUzQ2klMjBjbGFzcyUzRCUyMmZhJTIwZmEtZmFjZWJvb2slMjIlMjBhcmlhLWhpZGRlbiUzRCUyMnRydWUlMjIlM0UlM0MlMkZpJTNFJTNDJTJGYSUzRSUwQSUyMCUzQyUyRmxpJTNFJTBBJTIwJTIwJTIwJTNDbGklM0UlMEElMjAlMjAlMjAlM0NhJTIwaHJlZiUzRCUyMmh0dHBzJTNBJTJGJTJGd3d3LmxpbmtlZGluLmNvbSUyRmNvbXBhbnklMkZhbWVyaWNhbi13ZWItYnVpbGRlcnMlMkYlMjIlM0UlM0NpJTIwY2xhc3MlM0QlMjJmYS1icmFuZHMlMjBmYS1saW5rZWRpbi1pbiUyMiUzRSUzQyUyRmklM0UlM0MlMkZhJTNFJTBBJTIwJTNDJTJGbGklM0UlMEElM0NsaSUzRSUwQSUyMCUyMCUyMCUzQ2ElMjBocmVmJTNEJTIyaHR0cHMlM0ElMkYlMkZ3d3cuaW5zdGFncmFtLmNvbSUyRmFtZXJpY2Fud2ViYnVpbGRlcnMlMkYlMjIlM0UlM0NpJTIwY2xhc3MlM0QlMjJmYSUyMGZhLWluc3RhZ3JhbSUyMiUyMGFyaWEtaGlkZGVuJTNEJTIydHJ1ZSUyMiUzRSUzQyUyRmklM0UlM0MlMkZhJTNFJTBBJTIwJTNDJTJGbGklM0UlMEElMjAlMjAlM0NsaSUzRSUwQSUyMCUyMCUyMCUzQ2ElMjBocmVmJTNEJTIyaHR0cHMlM0ElMkYlMkZ0d2l0dGVyLmNvbSUyRmFtZXJpY2Fud2ViQVdCJTIyJTNFJTNDaSUyMGNsYXNzJTNEJTIyZmEtYnJhbmRzJTIwZmEteC10d2l0dGVyJTIyJTNFJTNDJTJGaSUzRSUzQyUyRmElM0UlMEElMjAlM0MlMkZsaSUzRSUwQSUzQyUyRnVsJTNFJTNDJTJGZGl2JTNF[\/vc_raw_html][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;6%&#8221; bottom_padding=&#8221;6%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][nectar_blog layout=&#8221;masonry-blog-fullwidth&#8221; blog_masonry_style=&#8221;material&#8221; load_in_animation=&#8221;fade_in_from_bottom&#8221; category=&#8221;all&#8221; enable_pagination=&#8221;true&#8221; pagination_type=&#8221;default&#8221; order=&#8221;DESC&#8221; orderby=&#8221;date&#8221; posts_per_page=&#8221;20&#8243;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][nectar_global_section id=&#8221;145&#8243;][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; id=&#8221;nec-sec&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221;&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-10","page","type-page","status-publish"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Blog | American Web Builders<\/title>\n<meta name=\"description\" content=\"American Web Builders bring latest information and trends about technology including development, Digital Marketing and Ecommerce\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.americanwebbuilders.com\/blog\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Blog | American Web Builders\" \/>\n<meta property=\"og:description\" content=\"American Web Builders bring latest information and trends about technology including development, Digital Marketing and Ecommerce\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.americanwebbuilders.com\/blog\/\" \/>\n<meta property=\"og:site_name\" content=\"American Web Builders\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-03T16:16:51+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.americanwebbuilders.com\\\/blog\\\/\",\"url\":\"https:\\\/\\\/www.americanwebbuilders.com\\\/blog\\\/\",\"name\":\"Blog | American Web Builders\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.americanwebbuilders.com\\\/blog\\\/#website\"},\"datePublished\":\"2023-05-17T06:19:24+00:00\",\"dateModified\":\"2026-08-03T16:16:51+00:00\",\"description\":\"American Web Builders bring latest information and trends about technology including development, Digital Marketing and Ecommerce\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.americanwebbuilders.com\\\/blog\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.americanwebbuilders.com\\\/blog\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.americanwebbuilders.com\\\/blog\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.americanwebbuilders.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"home\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.americanwebbuilders.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.americanwebbuilders.com\\\/blog\\\/\",\"name\":\"American Web Builders\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.americanwebbuilders.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Blog | American Web Builders","description":"American Web Builders bring latest information and trends about technology including development, Digital Marketing and Ecommerce","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.americanwebbuilders.com\/blog\/","og_locale":"en_US","og_type":"article","og_title":"Blog | American Web Builders","og_description":"American Web Builders bring latest information and trends about technology including development, Digital Marketing and Ecommerce","og_url":"https:\/\/www.americanwebbuilders.com\/blog\/","og_site_name":"American Web Builders","article_modified_time":"2026-08-03T16:16:51+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.americanwebbuilders.com\/blog\/","url":"https:\/\/www.americanwebbuilders.com\/blog\/","name":"Blog | American Web Builders","isPartOf":{"@id":"https:\/\/www.americanwebbuilders.com\/blog\/#website"},"datePublished":"2023-05-17T06:19:24+00:00","dateModified":"2026-08-03T16:16:51+00:00","description":"American Web Builders bring latest information and trends about technology including development, Digital Marketing and Ecommerce","breadcrumb":{"@id":"https:\/\/www.americanwebbuilders.com\/blog\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.americanwebbuilders.com\/blog\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.americanwebbuilders.com\/blog\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.americanwebbuilders.com\/blog\/"},{"@type":"ListItem","position":2,"name":"home"}]},{"@type":"WebSite","@id":"https:\/\/www.americanwebbuilders.com\/blog\/#website","url":"https:\/\/www.americanwebbuilders.com\/blog\/","name":"American Web Builders","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.americanwebbuilders.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.americanwebbuilders.com\/blog\/wp-json\/wp\/v2\/pages\/10","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.americanwebbuilders.com\/blog\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.americanwebbuilders.com\/blog\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.americanwebbuilders.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.americanwebbuilders.com\/blog\/wp-json\/wp\/v2\/comments?post=10"}],"version-history":[{"count":18,"href":"https:\/\/www.americanwebbuilders.com\/blog\/wp-json\/wp\/v2\/pages\/10\/revisions"}],"predecessor-version":[{"id":407,"href":"https:\/\/www.americanwebbuilders.com\/blog\/wp-json\/wp\/v2\/pages\/10\/revisions\/407"}],"wp:attachment":[{"href":"https:\/\/www.americanwebbuilders.com\/blog\/wp-json\/wp\/v2\/media?parent=10"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}